{"id":102,"date":"2007-03-02T15:19:08","date_gmt":"2007-03-02T14:19:08","guid":{"rendered":"http:\/\/reisen.mkihr.de\/index.php\/2007\/03\/02\/freitag-morgen\/"},"modified":"2007-03-02T15:19:08","modified_gmt":"2007-03-02T14:19:08","slug":"freitag-morgen","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2007\/03\/02\/freitag-morgen\/","title":{"rendered":"Freitag Morgen"},"content":{"rendered":"<p>Endlich Wochenende. Das beginnt am Freitag, dem moslemischen Sonntag. Die Stadt ist ziemlich Tot. Nix los, die meisten Gesch\u00e4fte geschlossen. Es gibt also nicht wirklich viel zu tun. Also haben wir uns, ein paar Kollegen, zu einem ordentlichen Freitags Fr\u00fchst\u00fcck verabredet und zwar so wie sich das geh\u00f6rt, mit Wei\u00dfwurst! Ein Kollege hat diese aus M\u00fcnchen mitgebracht. Also sassen wir bei strahlendem Sonnenschein im Garten eines lokalen Kollegen und haben Wei\u00dfwurst, Bier und anschlie\u00dfend noch einen Syrischen Kaffee genossen und dabei den Ges\u00e4ngen des Muezzin vom der nahe liegenden Moschee gelauscht. In Damaskus gibt es immer eine nahe liegende Moschee!<br \/>\n<a class=\"tt-flickr\" href=\"http:\/\/www.flickr.com\/photos\/mkihr\/407658284\"><img loading=\"lazy\" decoding=\"async\" class=\"tt-flickr\" src=\"http:\/\/farm1.static.flickr.com\/146\/407658284_e1bda630e2_m.jpg\" width=\"240\" height=\"180\" alt=\"P1020222.JPG\" \/><\/a> <a class=\"tt-flickr\" href=\"http:\/\/www.flickr.com\/photos\/mkihr\/407657529\"><img loading=\"lazy\" decoding=\"async\" class=\"tt-flickr\" src=\"http:\/\/farm1.static.flickr.com\/128\/407657529_6383522c2b_m.jpg\" width=\"240\" height=\"180\" alt=\"P1020216.JPG\" \/><\/a> <a class=\"tt-flickr\" href=\"http:\/\/www.flickr.com\/photos\/mkihr\/407658701\"><img loading=\"lazy\" decoding=\"async\" class=\"tt-flickr\" src=\"http:\/\/farm1.static.flickr.com\/180\/407658701_21ffdafa67_m.jpg\" width=\"240\" height=\"180\" alt=\"P1020225.JPG\" \/><\/a> <a class=\"tt-flickr\" href=\"http:\/\/www.flickr.com\/photos\/mkihr\/407658417\"><img loading=\"lazy\" decoding=\"async\" class=\"tt-flickr\" src=\"http:\/\/farm1.static.flickr.com\/132\/407658417_23e91cc137_m.jpg\" width=\"240\" height=\"180\" alt=\"Kaffee\" \/><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Endlich Wochenende. Das beginnt am Freitag, dem moslemischen Sonntag. Die Stadt ist ziemlich Tot. Nix los, die meisten Gesch\u00e4fte geschlossen. Es gibt also nicht wirklich viel zu tun. Also haben wir uns, ein paar Kollegen, zu einem ordentlichen Freitags Fr\u00fchst\u00fcck verabredet und zwar so wie sich das geh\u00f6rt, mit Wei\u00dfwurst! Ein Kollege hat diese aus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-102","post","type-post","status-publish","format-standard","hentry","category-syrien"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=102"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/102\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}