{"id":118,"date":"2007-07-31T21:11:19","date_gmt":"2007-08-01T02:11:19","guid":{"rendered":"http:\/\/reisen.mkihr.de\/index.php\/2007\/07\/31\/ja-ja-ich-bin-faul\/"},"modified":"2007-07-31T21:11:19","modified_gmt":"2007-08-01T02:11:19","slug":"ja-ja-ich-bin-faul","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2007\/07\/31\/ja-ja-ich-bin-faul\/","title":{"rendered":"Ja, ja, ich bin faul"},"content":{"rendered":"<p>In der Tat hab ich in den letzten beiden Wochen ein bisschen wenig geschrieben. Man kann sogar behaupten: gar nicht. Es gab aber in den letzten Tagen ein paar Ereignisse von denen ich jetzt doch mal berichten will. Diese folgen in B\u00e4lde! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der Tat hab ich in den letzten beiden Wochen ein bisschen wenig geschrieben. Man kann sogar behaupten: gar nicht. Es gab aber in den letzten Tagen ein paar Ereignisse von denen ich jetzt doch mal berichten will. Diese folgen in B\u00e4lde!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,33,16],"tags":[],"class_list":["post-118","post","type-post","status-publish","format-standard","hentry","category-amerika","category-peru","category-sud-amerkia"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=118"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/118\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}