{"id":124,"date":"2007-09-23T08:52:01","date_gmt":"2007-09-23T08:52:01","guid":{"rendered":"http:\/\/reisen.mkihr.de\/index.php\/2007\/09\/23\/etwas-hektische-fliegerei\/"},"modified":"2007-09-23T08:52:01","modified_gmt":"2007-09-23T08:52:01","slug":"etwas-hektische-fliegerei","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2007\/09\/23\/etwas-hektische-fliegerei\/","title":{"rendered":"Etwas hektische Fliegerei"},"content":{"rendered":"<p>Allerdings ging&#8217;s erst mal wenig hektisch zu.  Als ich in Berlin am Flughafen ankam, teilte mir die Informationstafel \u00fcber dem Checkin mit, dass der Flug eine Stunde versp\u00e4tet sei. Auch nicht schlecht. Erst mal noch Zeit f\u00fcr ein bisschen Zeitung lesen und und was trinken. Um die Zeit zu \u00fcberbr\u00fccken gabs bich eien 8 Euro Gutschein f\u00fcr Getr\u00e4nke. Obwohl die in der Longe eh umsonst sind, hab den auch noch mitgenommen und an der Bar in der Empfangshalle noch einen gezwitschert. Aber viel geht da mit 8 Euro auch nicht.<br \/>\nHab mich dann wieder p\u00fcnktlich zum einsteigen am Gate eingefunden. Der Bildschirm zeigte: Flug von 17:40 versp\u00e4tet. Boarding 18:40, Abflug 19:10. Es war bereits 18:35. Der Flieger war aber noch gar nicht da. Einsteigen um 18:40 erschien also nicht sehr wahrscheinlich. Etwas sp\u00e4ter kam der Flieger dann an. Das aussteigen zog sich. Es war inzwischen nach 19:00 Uhr und das Einsteigen hatte noch immer nicht begonnen. Ich rechne mal nach: 19:30 los. Eine Stunde Flug. 20:30 in Amsterdam. Aussenposition, also mit dem Bus zum Gate. Ist in Amsterdam bei Kurzstreckenfl\u00fcgen normal. Also noch mal 10 Minuten. Bleiben 20 Minuten. In dieser Zeit einmal quer durchs Flughafengeb\u00e4ude, durch die Grenzkontrolle und den Sicherheitscheck. Normalerweise wird f\u00fcr den Weg eine Zeit von ca. 40 Minuten veranschlagt. Nicht davon zu reden, dass das Gep\u00e4ck mindestens 45 Minuten braucht. Ich frage mal vorsichtig das Personal, was mit den Anschlussfl\u00fcgen ist. Die haben keine Ahnung. Es gibt noch ein paar andere, die noch fr\u00fchere Anschl\u00fcsse haben. Auskunft kann aber keiner geben. Die wissen nicht mal, wie weit der Weg in Amsterdam von der Ankunft zum Abflug ist.<br \/>\nEndlich k\u00f6nnen wir einsteigen. Meine Sch\u00e4tzung war gut! 19:30 Uhr gehts los. Flugzeit soll eine Stunde sein.<br \/>\nDas Personal im Flieger weiss auch nix \u00fcber Anschlussfl\u00fcge. 20:15 eine Ansage: Landung ist in 20 Minuten. Dann noch ca. 10 Minuten Rollweg bis zum Halteplatz. Von dort mit dem Bus. Also gegen 20:50 etwa am Gate. Ich gebe meinen Anschluss auf. Dazu dann noch die Auskunft: Alle Flieger nach 21:10 werden erreicht. Die anderen Passagiere wenden sich bitte an die Auskunft. Na toll.<br \/>\nDann gibts aber doch noch eine positive \u00dcberraschung: Am Gate steht tats\u00e4chlich eine Dame und sammelt die Passagiere ein, die den Flug nach Kuala Lumpur\/Jakarta verpasst haben. Wir sollen mit einem anderen nach Singapore fliegen und von dort dann weiter. In meinem Falle mit der Lufthansa. Ich w\u00fcrde mit knapp einer Stunde Versp\u00e4tung in Jakarta ankommen. Nachdem sich alle, die das betraf, eingefunden hatten ging eine wilde Rennerei durch den Flughafen los. Den Flieger nach Singapore gerade noch mit heraush\u00e4ngender Zunge erreicht. Dann erst mal 12 Stunden Entspannung vor der n\u00e4chsten Hetzerei. Angekommen habe ich erst mal den Transferschalter der Lufthansa gesucht. Ich musste ja noch f\u00fcr den Flug einchecken. Zeit gerade mal 40 Minuten. Ich finde den Transferschalter, dort allerdings nur die Info, das die Lufthansa im anderen Terminal residiert. Also wieder die F\u00fcsse in die Hand. Quer durch das ganze Geb\u00e4ude. Dann mit dem Skytrain ins andere Terminal und dann wieder zum Transfer. Endlich ein Lufthansaschalter. Geschlossen. Die Kollegin sei gerade mal nicht da. Ich trug mein Begehr vor. Einchecken nach Jakarta. Die Kollegin sei halt nicht da. W\u00fcrde so ca. 10 Minuten dauern. Aber dann sei ohnehin das Gate geschlossen. Ich sei halt etwas sp\u00e4t dran. Ich denke ich h\u00f6re schlecht. Weil die Kollegin nicht da ist, soll ich schon wieder den Flug verpassen? Ich reagiere etwas ungehalten und nach einiger Diskussion wurde ich dann von einem der vielen herumstehenden Uniformierten eingecheckt. Dann noch mal rennen bis zum Gate und endlich geschafft.<\/p>\n<p>\u00dcbrigens: Das mit dem Pickup hat diesmal, trotz der Versp\u00e4tung, geklappt. Eine noch viel gr\u00f6ssere \u00dcberraschung war allerdings: Sogar mein Gep\u00e4ck hatte den Weg zusammen mit mir nach Jakarta gefunden. Das hatte ich wirklich nicht erwartet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Allerdings ging&#8217;s erst mal wenig hektisch zu. Als ich in Berlin am Flughafen ankam, teilte mir die Informationstafel \u00fcber dem Checkin mit, dass der Flug eine Stunde versp\u00e4tet sei. Auch nicht schlecht. Erst mal noch Zeit f\u00fcr ein bisschen Zeitung lesen und und was trinken. Um die Zeit zu \u00fcberbr\u00fccken gabs bich eien 8 Euro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,29,17],"tags":[],"class_list":["post-124","post","type-post","status-publish","format-standard","hentry","category-asien","category-indonesien","category-sud-ost-asien"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=124"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/124\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}