{"id":125,"date":"2007-09-25T16:34:33","date_gmt":"2007-09-25T09:34:33","guid":{"rendered":"http:\/\/reisen.mkihr.de\/index.php\/2007\/09\/25\/diese-stadt-ist-der-wahnsinn\/"},"modified":"2007-09-25T16:34:33","modified_gmt":"2007-09-25T09:34:33","slug":"diese-stadt-ist-der-wahnsinn","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2007\/09\/25\/diese-stadt-ist-der-wahnsinn\/","title":{"rendered":"Diese Stadt ist der Wahnsinn"},"content":{"rendered":"<p>Ich bin ja nun nicht zum ersten mal hier.  Mein letzter Besuch in dieser Stadt liegt aber trotzdem schon fast ein Jahr zur\u00fcck. Es ist absolut irre, wie sehr sich diese Stadt in der kurzen Zeit ver\u00e4ndert. Direkt hinter dem Hotel steht ein Hochhaus von dem vor einem Jahr gerade mal etwas mehr als die Baugrube zu sehen war. Im Stadtzentrum entsteht ein Wolkenkratzer neben dem anderen. Im &#8222;goldenen Triangel&#8220;, rings um Kuningan und entlang der Casablanca steht ein B\u00fcroneubau und ein neues Hotel neben dem anderen. Aus dem einen Busway von vor 2 Jahren sind inzwischen 5 Linien geworden die in der Hauptverkehrszeit im Minutentakt unterwegs sind. Das entlastet zwar den Stra\u00dfenverkehr noch nicht wirklich. Es gibt noch immer viel zu viel chaotischen Individualverkehr. Normalerweise ist man aber mit dem Bus durch die Stadt sehr viel schneller unterwegs als mit dem Auto. Die Buslinien sind hier schon bewusst so angelegt, dass die Busspur nicht so einfach vom Autos zu befahren ist, indem sie baulich abgetrennt wurden (siehe Foto) <a href=\"http:\/\/www.flickr.com\/photos\/mkihr\/1544210754\" class=\"tt-flickr\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2272\/1544210754_8c3c2482f6_m.jpg\" alt=\"P1000341\" align=\"left\" border=\"2\" height=\"180\" hspace=\"2\" vspace=\"2\" width=\"240\" \/><\/a><br \/>\nDie Indonesier kennen halt ihre Mitmenschen ;). Allerdings hilft auch das nicht vollst\u00e4ndig. An Kreuzungen z.B. gibt es durchaus die M\u00f6glichkeit in die Busspur hineinzufahren und es gibt tats\u00e4chlich solche r\u00fccksichtslosen Idioten hier, die das tats\u00e4chlich tun und dann eben auch die Busspur zustauen und damit den Vorteil wieder zunichte machen. Aber es ist ja nicht neu, dass man sich hier gegen\u00fcber der Allgemeinheit sehr R\u00fccksichtslos benimmt. Jeder lebt hier so, als w\u00e4re er alleine auf der Welt. Daran hat sich noch immer nichts ge\u00e4ndert. Wer der Meinung ist, dass man sich auf Deutschlands Strassen aggressiv und r\u00fccksichtslos Benimmt, der sollte unbedingt mal hier her kommen. Wenn es ihm dann hier gelingt am Semanggi   Interchange von Panchoran kommend zur Plaza Semanggi einzubiegen ohne zu fluchen und feuchte H\u00e4nde zu bekommen und ohne einen Motorradfahrer umzunieten, dann kann er von sich behaupten, er kann Auto fahren. Ich kann&#8217;s nicht!<br \/>\n<a href=\"http:\/\/www.flickr.com\/photos\/mkihr\/1544210410\" class=\"tt-flickr\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2108\/1544210410_23ccd65658_m.jpg\" alt=\"P1000340\" align=\"bottom\" border=\"2\" height=\"180\" hspace=\"2\" vspace=\"2\" width=\"240\" \/><\/a><a href=\"http:\/\/www.flickr.com\/photos\/mkihr\/1544213476\" class=\"tt-flickr\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2003\/1544213476_17ba7a1cb5_m.jpg\" alt=\"P1000352\" align=\"bottom\" border=\"2\" height=\"180\" hspace=\"2\" vspace=\"2\" width=\"240\" \/><\/a><\/p>\n<p>Auf den Bildern zwei v\u00f6llig normale Stra\u00dfenszenen  in Jakarta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich bin ja nun nicht zum ersten mal hier. Mein letzter Besuch in dieser Stadt liegt aber trotzdem schon fast ein Jahr zur\u00fcck. Es ist absolut irre, wie sehr sich diese Stadt in der kurzen Zeit ver\u00e4ndert. Direkt hinter dem Hotel steht ein Hochhaus von dem vor einem Jahr gerade mal etwas mehr als die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,17],"tags":[68,80,132,141],"class_list":["post-125","post","type-post","status-publish","format-standard","hentry","category-indonesien","category-sud-ost-asien","tag-bau","tag-busway","tag-indoensien","tag-jakarta"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=125"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/125\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}