{"id":136,"date":"2007-10-27T13:05:01","date_gmt":"2007-10-27T05:05:01","guid":{"rendered":"http:\/\/reisen.mkihr.de\/index.php\/2007\/10\/27\/nach-puerto-galera\/"},"modified":"2007-10-27T13:05:01","modified_gmt":"2007-10-27T05:05:01","slug":"nach-puerto-galera","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2007\/10\/27\/nach-puerto-galera\/","title":{"rendered":"Nach Puerto Galera"},"content":{"rendered":"<p align=\"justify\">Hab mich also heute auf den Weg gemacht. Schon um 6 aufgestanden. Fr\u00fchst\u00fcck. Dann zum Bus. War p\u00fcnktlich da. Mit dem Bus geht es einmal quer durch Manila. Ist aber gar nicht so schlimm. Der Bus nimmt den sogenannten &#8222;Sky Way&#8220;. Das ist eine neue Mautstra\u00dfe die nicht deshalb &#8222;Sky Way&#8220; hei\u00dft weil man augf ihr fliegen kann, sondern weil sie auf Betonpfeilern hoch \u00fcber allen anderen Stra\u00dfen der Stadt verl\u00e4uft. Macht nicht wirklich ein sch\u00f6nes Bild, ist aber schnell. Bis zur F\u00e4hre sind es ca. 2,5 Stunden \u00fcber Land. Viel zu sehen gibt es nicht.<br \/>\n<a href=\"http:\/\/www.flickr.com\/photos\/mkihr\/1799387074\" class=\"tt-flickr\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2043\/1799387074_6d561dc039_m.jpg\" alt=\"P1000477\" align=\"left\" border=\"2\" height=\"180\" hspace=\"2\" vspace=\"2\" width=\"240\" \/><\/a> Die F\u00e4hre ist dann doch etwas womit ich so nicht gerechnet hatte (siehe Foto). Ein etwas gr\u00f6sseres traditionelles Holzboot. Bambusst\u00fctzen an den Seiten (erinnert etwas an ein Fahrrad mit St\u00fctzr\u00e4dern). War schon ziemlich gef\u00fcllt. Nichts desto trotz wurde auch der Inhalt des Bus noch hinein gezw\u00e4ngt. Samt Gep\u00e4ck. Schien das Ding aber auszuhalten. Rauf gings \u00fcber eine schmale, steile Planke. Diese war aber, um es den Passagieren leichter zu machen, mit Sprossen wie eine H\u00fchnerleiter ausgestattet. Au\u00dferdem war fast alles wo man hintreten konnte mit einem rutschfesten Belag versehen. Die Bootsmannschaft war auch recht hilfreich. Die haben beim klettern ein bisschen geholfen. War auch n\u00f6tig. Ich Trottel habe meinen Fu\u00df nat\u00fcrlich dahin gesetzt wo kein Belag war. Hab den schweren Fehler leider erst einen Augenblick zu sp\u00e4t bemerkt. Es war f\u00fcrchterlich glatt.  Beinahe endete die Kletterei im Wasser. Es h\u00e4tte spektakul\u00e4r ausgesehen. War es wahrscheinlich auch. Hat eben nur der Kr\u00f6nende Schluss gefehlt.<br \/>\nDie \u00dcberfahrt war recht angenehm. Kaum Wellengang. Der Fahrtwind machte die Temperatur gut ertr\u00e4glich. Nach ca. 1 Stunde legten wir das erste mal an. Hier konnte man auch sehen, warum ein solches Boot als F\u00e4hre verwendet wurde. Wir legten direkt am Strand an. <a href=\"http:\/\/www.flickr.com\/photos\/mkihr\/1798554821\" class=\"tt-flickr\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2076\/1798554821_6572021f58_m.jpg\" alt=\"P1000549\" align=\"right\" border=\"2\" height=\"180\" hspace=\"2\" vspace=\"2\" width=\"240\" \/><\/a> Einfach wieder die Planke raus und alles von Bord. Dachte ich. Am Stand hab ich dann nach dem Typen gesucht, der mich abhohlen sollte. Konnte ich aber nicht finden. Irgendwann fragte mich dann jemand, wo ich hin will. &#8222;Blue Crystal Beach!&#8220; Sie riss die Augen auf: &#8222;Das ist aber nicht hier! In Puerto Galera! Das hier ist Sabang! Sie m\u00fcssen weiter mit der F\u00e4hre. Gab halt nur ein Problem. Die hatte schon wieder abgelegt. Gott sei Dank war sie noch in Rufweite. Sie kam noch mal zur\u00fcck. Ich wieder \u00fcber die Planke, immer sch\u00f6n auf dem Kunststoff. 15 Minuten sp\u00e4ter waren wir in Puerto Galera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hab mich also heute auf den Weg gemacht. Schon um 6 aufgestanden. Fr\u00fchst\u00fcck. Dann zum Bus. War p\u00fcnktlich da. Mit dem Bus geht es einmal quer durch Manila. Ist aber gar nicht so schlimm. Der Bus nimmt den sogenannten &#8222;Sky Way&#8220;. Das ist eine neue Mautstra\u00dfe die nicht deshalb &#8222;Sky Way&#8220; hei\u00dft weil man augf [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,34,17],"tags":[105,197,201],"class_list":["post-136","post","type-post","status-publish","format-standard","hentry","category-asien","category-philippinen","category-sud-ost-asien","tag-fahre","tag-philippinen","tag-puerto-galera"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/136\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}