{"id":263,"date":"2008-12-31T07:39:07","date_gmt":"2008-12-31T00:39:07","guid":{"rendered":"http:\/\/reisen.mkihr.de\/?p=263"},"modified":"2008-12-31T07:39:07","modified_gmt":"2008-12-31T00:39:07","slug":"sky-dining","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2008\/12\/31\/sky-dining\/","title":{"rendered":"Sky Dining"},"content":{"rendered":"<div id=\"attachment_264\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-264\" class=\"size-medium wp-image-264\" title=\"p1020075\" src=\"http:\/\/reisen.mkihr.de\/wp-content\/uploads\/2008\/12\/p1020075-300x225.jpg\" alt=\"Blick in Richtung Westen (Slipi)\" width=\"300\" height=\"225\" \/><p id=\"caption-attachment-264\" class=\"wp-caption-text\">Blick in Richtung Westen (Slipi)<\/p><\/div>\n<p>Eine der Malls in der ich recht oft bin, ist die Plaza Semanggi. Auch Plangi genannt. Das liegt ganz einfach daran, das diese sehr g\u00fcnstig zu erreichen ist. Es ist fast egal, von wo nach wo man in dieser Stadt f\u00e4hrt, man kommt beinahe immer daran vorbei. Sie liegt direkt am Semanggi Interchange wo sich zwei der wichtigsten Strassen der Stadt kreuzen. Au\u00dferdem liegt sie sehr nahe an dem Hotel, welches ich \u00fcblicherweise benutze und auch gleich um die Ecke vom neuen NSN Office. Vom Menara Mulia k\u00f6nnte man praktisch dorthin laufen, wenn man in dieser Stadt laufen k\u00f6nnte.<br \/>\nDie Plaza Semanggi ist eine der \u00e4lteren Malls in dieser Stadt und hat noch nicht solche ausgefallen Dinge zu bieten wie Eislaufen oder Boot fahren. Allerdings gibt es jetzt seit einiger Zeit das sogenannte &#8222;Sky Dining&#8220;. Hier wurde einfach ein Teil das Parkdecks der 10. Etage in eine Restaurant Au\u00dfenfl\u00e4che umgewandelt. Es gibt einige restaurants und Cafes hier. &#8222;Sky Dining&#8220; klingt gewaltiger als es ist. Die 10. Etage ist nicht gerade der Himmel und die Restaurants sind von eher mittlerem Niveau. Solaria geh\u00f6rt unter anderem dazu. Eine Kette mit indonesischem Essen. Preiswert und gut aber f\u00fcr Ausl\u00e4nder ohne Kenntnisse des indonesischen Essens und der Sprache eher nicht zu empfehlen. Das Personal spricht in der Regel kein englisch und auch die Karte gibt es nur in Bahasa. Wenn man nicht wei\u00df was &#8222;Nasi Goreng Pete&#8220; ist, sollte man lieber vorsichtig sein.\u00a0 Die Wirkung ist unter umst\u00e4nden nicht ganz das, was man erwartet.<\/p>\n<div id=\"attachment_265\" style=\"width: 310px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-265\" class=\"size-medium wp-image-265\" title=\"p1020077\" src=\"http:\/\/reisen.mkihr.de\/wp-content\/uploads\/2008\/12\/p1020077-300x225.jpg\" alt=\"Blick nach S\u00fcden (Senajan)\" width=\"300\" height=\"225\" \/><p id=\"caption-attachment-265\" class=\"wp-caption-text\">Blick nach S\u00fcden (Senajan)<\/p><\/div>\n<p>\u00c4hnlich ist es mit dem &#8222;Comedy Cafe&#8220;. Es ist das erste in der Reihe, wenn man vom Fahrstuhl kommt. Es ist fast nicht m\u00f6glich daran vorbei zu kommen. Der Typ der dort vor der T\u00fcr steht um G\u00e4ste zu gewinnen, ist fast nicht zu \u00fcberwinden. Der spricht englisch. Auch das andere Personal. Man kommt auch mit dem Essen klar. Es gibt durchaus Speisen, die man kennt. Allerdings wird es mit der Comedy schwierig. Da ist nix mit englisch. Au\u00dferdem versuchen die st\u00e4ndig, einen zum mitmachen zu bringen. Wenn man da die Sprache nicht versteht, ist man ganz schnell der Lacher des Tages.<br \/>\nNaja, aber ich will hier nicht alle ver\u00e4ngstigen. Der Platz ist durchaus einen Besuch wert. Die 10. Etage ist nicht wirklich hoch, aber die Sicht ist wirklich gut. Man hat einen freien Blick in Richtung S\u00fcden, da sich genau dort die schon genannte gro\u00dfe Kreuzung befindet. Der Blick kann hier nicht verbaut werden. Es ist durchaus angenehm hier im freien zu Sitzen. Es gibt Sonnenschutz, es weht ein angenehmes L\u00fcftchen und erstaunlicherweise ist vom L\u00e4rm, Gestank und Dreck der Strasse schon in dieser H\u00f6he nichts zu h\u00f6ren und nicht zu riechen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine der Malls in der ich recht oft bin, ist die Plaza Semanggi. Auch Plangi genannt. Das liegt ganz einfach daran, das diese sehr g\u00fcnstig zu erreichen ist. Es ist fast egal, von wo nach wo man in dieser Stadt f\u00e4hrt, man kommt beinahe immer daran vorbei. Sie liegt direkt am Semanggi Interchange wo sich [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[54,134,141,219,226],"class_list":["post-263","post","type-post","status-publish","format-standard","hentry","category-indonesien","tag-asien","tag-indonesien","tag-jakarta","tag-semanggi","tag-sky-dining"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}