{"id":27,"date":"2005-10-14T20:32:00","date_gmt":"2005-10-14T18:32:00","guid":{"rendered":"http:\/\/www.mkihr.de\/wordpress\/?p=27"},"modified":"2005-10-14T20:32:00","modified_gmt":"2005-10-14T18:32:00","slug":"soekarnos-letzte-erektion","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2005\/10\/14\/soekarnos-letzte-erektion\/","title":{"rendered":"Soekarnos letzte Erektion"},"content":{"rendered":"<p><a href=\"http:\/\/photos1.blogger.com\/blogger\/3912\/1353\/1600\/smog.jpg\"><img decoding=\"async\" src=\"http:\/\/photos1.blogger.com\/blogger\/3912\/1353\/200\/smog.jpg\" alt=\"\" border=\"0\" \/><\/a><br \/>\n<a href=\"http:\/\/photos1.blogger.com\/blogger\/3912\/1353\/1600\/P1000124.jpg\"><img decoding=\"async\" src=\"http:\/\/photos1.blogger.com\/blogger\/3912\/1353\/200\/P1000124.jpg\" alt=\"\" border=\"0\" \/><\/a><br \/>\n<a href=\"http:\/\/photos1.blogger.com\/blogger\/3912\/1353\/1600\/Monas.jpg\"><img decoding=\"async\" src=\"http:\/\/photos1.blogger.com\/blogger\/3912\/1353\/200\/Monas.jpg\" alt=\"\" border=\"0\" \/><\/a><br \/>\nNein! Das wird jetzt kein Auszug aus der pornografischen Geschichte Indonesiens. Die Indonesier nennen ihr National Monument so. Es wurde 1961 noch unter dem ersten Pr\u00e4sidenten Soekarno gebaut, liegt mitten in Jakarta und ist fast das einzige park\u00e4hnliche Gebilde in der Stadt. Park\u00e4hnlich deshalb, weil es im Gegensatz zu einem richtigen Park weitestgehend zubetoniert ist. Trotzdem lohnt sich ein Weg dorthin. Zum einen gibt es um den \u201ePark\u201c noch einige andere Dinge zu sehen. Den Pr\u00e4sidentenpalast gleich am nordwestlichen Ausgang und im Nordosten die Istiquial Moschee. Die gr\u00f6\u00dfte in S\u00fcdostasien. Sehenswert ist das Monument vor allem Nachts (siehe Foto). Am Tage lohnt sich eine Fahrt zur Aussichtsplattform. Es ist wohl einer der besten Aussichtspunkte der Stadt. Allerdings ist das, wie vieles in diesem Land, nicht ganz einfach. Man kommt aus dem Stadtzentrum am besten bis dem Transjakarta hier her. Allerdings liegt die Station \u201eMonument National\u201c abseits von jedem Eingang in den Park. Offen sind n\u00e4mlich normalerweise nur die Tore an den Ecken. Die Busstation liegt exakt in der Mitte dazwischen. Auch vom n\u00f6rdlichen und s\u00fcdlichen Ende liegen die Haltestellen recht weit entfernt. Warum das so ist, weis wohl nur Allah. Es ist also erst mal ein paar hundert Meter laufen angesagt. Damit sind die Schwierigkeiten aber noch nicht vorbei. Jetzt muss man den Eingang zum Monument finden. Wenn man aus Richtung Norden kommt, sieht das auf den Ersten Blick sehr einfach aus. Das Monument steht auf einem Sockel. Am Fu\u00df des Monuments ist ein recht gro\u00dfes Tor zu sehen. Also hin. Geht aber nicht. Um den ganzen Sockel ist ein Zaun. Keine T\u00fcr, kein Loch, kein Weg zum Tor. Ich bin einmal rings rum. Nix zu machen. Aber ich sehe Leute am Tor. Sind die geflogen? Als ich es auch schon versuchen wollte ab ich den Weg entdeckt. Ungef\u00e4hr 150m n\u00f6rdlich vom Turm gibt ein unscheinbares Loch in der Erde. Davor noch ein unscheinbareres Schild (ca. 30 cm) mit der Aufschrift \u201eMasuk\u201c (Eingang) und einem Pfeil nach unten. Na gut. Also unter die Erde. Hier gibt es so etwas wie ein atombombensicheres Kassenh\u00e4uschen. Nach Entrichtung eines Eintrittspreises von 5000 Rupia (ca. 45 Cent) und einer Versicherung von 100 Rupia kann man dann durch einen langen Gang zum Turm gelangen. Wogegen man mit den 100 Rupia versichert ist, kann mir keiner so genau sagen. Die haben wohl Angst, dass der St\u00e4ngel umf\u00e4llt, wenn so ein Leichtgewicht wie ich die Plattform einseitig belastet.<br \/>\nDer restliche Weg ist vergleichswei\u00dfe Einfach, wenn auch recht verschlungen. Nach oben kommt man mit einem Lift. Die Aussicht ist ganz gut, allerdings ziemlich tr\u00fcbe (siehe Foto). Ich muss dazu sagen, es war ein recht sch\u00f6ner Tag mit klarem Himmel und Sonnenschein. Was aussieht wie Nebel, ist die Luft die man in dieser Stadt atmet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nein! Das wird jetzt kein Auszug aus der pornografischen Geschichte Indonesiens. Die Indonesier nennen ihr National Monument so. Es wurde 1961 noch unter dem ersten Pr\u00e4sidenten Soekarno gebaut, liegt mitten in Jakarta und ist fast das einzige park\u00e4hnliche Gebilde in der Stadt. Park\u00e4hnlich deshalb, weil es im Gegensatz zu einem richtigen Park weitestgehend zubetoniert ist. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-27","post","type-post","status-publish","format-standard","hentry","category-indonesien"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=27"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=27"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}