{"id":389,"date":"2009-02-01T19:54:53","date_gmt":"2009-02-01T12:54:53","guid":{"rendered":"http:\/\/reisen.mkihr.de\/?p=389"},"modified":"2009-02-01T19:54:53","modified_gmt":"2009-02-01T12:54:53","slug":"gombal","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2009\/02\/01\/gombal\/","title":{"rendered":"Gombel"},"content":{"rendered":"<p><a class=\"tt-flickr\" href=\"http:\/\/www.flickr.com\/photos\/mkihr\/3244059260\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft tt-flickr\" style=\"float: left; margin-left: 4px; margin-right: 4px;\" src=\"http:\/\/farm4.static.flickr.com\/3127\/3244059260_77b8c24306_m.jpg\" alt=\"Blick von Gombel, Semarang\" width=\"240\" height=\"180\" \/><\/a> heisst die Gegend von Semarang wo wir arbeiten. Ca. 30 Minuten vom Hotel. Hoch \u00fcber der Stadt gelegen hat man eine gro\u00dfartige Sicht \u00fcber die Stadt bis hin zur Java See. Sie liegt an der Strasse die von Semarang Richtung S\u00fcden nach Solo und Yogjakarta f\u00fchrt.<br \/>\nDa die Zeit etwas dr\u00e4ngt, haben wir auch heute gearbeitet. Gegen 16:00 Uhr waren wir dann fertig und sind in einem der Restaurants an der Strasse die den Berg hinauf f\u00fchrt Essen gegangen. Der Weg dorthin ist nicht ganz ohne. Taxi dorthin zu fahren lohnt sich nicht. Sind nur ein paar hundert Meter.[ad]<!--more--><\/p>\n<p>Das Problem allerdings ist, das es keinen Fussweg gibt. Man muss sich die Strasse mit dem nicht gerade geringen Verkehr auf dieser Strasse teilen. Und auch hier erweisen sich nicht die Autos sondern einmal mehr die Mopeds als Problem. Aber wir haben es geschafft. Der Aussicht ist gut, wenngleich das was es zu sehen gibt nicht wirklich als &#8222;sch\u00f6n&#8220; zu bezeichnen ist. Der Himmel ist grau. Na Gut. Daf\u00fcr kann man w\u00e4hrend der Regenzeit nicht wirklich jemand verantwortlich machen.<\/p>\n<p><a class=\"tt-flickr\" href=\"http:\/\/www.flickr.com\/photos\/mkihr\/3244056932\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright tt-flickr\" style=\"float: right; margin-left: 4px; margin-right: 4px;\" src=\"http:\/\/farm4.static.flickr.com\/3459\/3244056932_fa77e97297_m.jpg\" alt=\"Blick von Gombel, Semarang\" width=\"240\" height=\"180\" \/><\/a> Aber die Stadt liegt in einem schmutzig grauen Dunst. Der Blick reicht bis zum Meer und dort kann man genau sehen, wo Fl\u00fcsse und die Java See m\u00fcnden. Dort ist das Wasser irgendwie zwischen braun, grau und schwarz eingef\u00e4rbt. Weiter drau\u00dfen wird es dann blau.<br \/>\nZu essen gibt es gegrillten Gurame (Fisch) und King Prawn&#8217;s. Hoffentlich alles etwas weiter drau\u00dfen, im klaren Wasser gefangen.<br \/>\nMorgen werden wir noch ein bisschen hier zu tun haben. Dann gehts es schon wieder zur\u00fcck nach Jakarta. Daniel wird weiter nach Surabaya fliegen und dort die Anlage in Betrieb nehmen, ich werde die Installation f\u00fcr Semarang aus Jakarta fortsetzen.<\/p>\n<p>GPS Koordinaten: INSERT_COORDS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>heisst die Gegend von Semarang wo wir arbeiten. Ca. 30 Minuten vom Hotel. Hoch \u00fcber der Stadt gelegen hat man eine gro\u00dfartige Sicht \u00fcber die Stadt bis hin zur Java See. Sie liegt an der Strasse die von Semarang Richtung S\u00fcden nach Solo und Yogjakarta f\u00fchrt. Da die Zeit etwas dr\u00e4ngt, haben wir auch heute [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,29,17],"tags":[118,119,189,220],"class_list":["post-389","post","type-post","status-publish","format-standard","hentry","category-asien","category-indonesien","category-sud-ost-asien","tag-gombal","tag-gombel","tag-novotel","tag-semarang"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=389"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/389\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}