{"id":422,"date":"2009-02-07T16:23:10","date_gmt":"2009-02-07T09:23:10","guid":{"rendered":"http:\/\/reisen.mkihr.de\/?p=422"},"modified":"2009-02-07T16:23:10","modified_gmt":"2009-02-07T09:23:10","slug":"nochmal-kopi-luwak","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2009\/02\/07\/nochmal-kopi-luwak\/","title":{"rendered":"Noch mal Kopi Luwak"},"content":{"rendered":"<p>Nur noch mal ein paar Infos f\u00fcr denjenigen den es interessieren sollte. Inzwischen habe ich herausgefunden wo es den originalen Kaffee auch zu mit nach Hause nehmen zu kaufen gibt. Die Kaffeehaus Kette &#8222;Kopi Luwak&#8220; bietet auch den &#8222;echten&#8220; Kaffee Luwak an. Man muss zwar etwas aufpassen. Auch der ganz normale Kaffee hei\u00dft dort &#8222;Kopi Luwak&#8220;. Der spezielle steht auch nicht in der Karte. Man muss danach fragen. Dann wird einem dieser Kaffee direkt am Tisch zubereitet. Aus einem versiegelten Beutelchen kommt der gemahlene Kaffee in die Tasse. Dann wird er mit heisem Wasser \u00fcbergossen und nach 2 Minuten warten ist das ganze fertig.<!--more--><\/p>\n<p>Man kann den Kaffee allerdings auch zum mitnehmen erwerben. Es gibt Geschenkpackungen mit Tasse und 150 oder 200 Gramm Kaffee. Oder auch nur den Kaffee. Das ganze kostet zwichen 50 und 100 $. [ad]<\/p>\n<p>Outlets dieser Kaffee Kette, die ich kenne sind:<\/p>\n<p>Flughafen Semerang im Abflugbereich<br \/>\nPacific Place Jakarta, LG #9<br \/>\nFX Mall Senayan, Ground Floor<br \/>\nKelapa Gading Mall 2, Ground Floor #28<\/p>\n<p>Das Bild \u00fcbrigens zeigt den nicht echten &#8222;Kopi Luwak&#8220;. Diesen gibt es in jedem Markt hier zu kaufen und 200 Gramm kosten ca. 3 Euro. Dieses Zeug wird aber teilweise bei ebay als Kaffee Luwak angeboten. Also Vorsicht!<\/p>\n<div id=\"attachment_423\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/reisen.mkihr.de\/wp-content\/uploads\/2009\/02\/grounddarkroasted.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-423\" class=\"size-medium wp-image-423\" title=\"grounddarkroasted\" src=\"http:\/\/reisen.mkihr.de\/wp-content\/uploads\/2009\/02\/grounddarkroasted-300x200.jpg\" alt=\"Der &quot;falsche&quot; Kopi Luwak\" width=\"300\" height=\"200\" \/><\/a><p id=\"caption-attachment-423\" class=\"wp-caption-text\">Der &quot;falsche&quot; Kopi Luwak<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nur noch mal ein paar Infos f\u00fcr denjenigen den es interessieren sollte. Inzwischen habe ich herausgefunden wo es den originalen Kaffee auch zu mit nach Hause nehmen zu kaufen gibt. Die Kaffeehaus Kette &#8222;Kopi Luwak&#8220; bietet auch den &#8222;echten&#8220; Kaffee Luwak an. Man muss zwar etwas aufpassen. Auch der ganz normale Kaffee hei\u00dft dort &#8222;Kopi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,17],"tags":[83,141,157,220,221],"class_list":["post-422","post","type-post","status-publish","format-standard","hentry","category-indonesien","category-sud-ost-asien","tag-coffee","tag-jakarta","tag-kopi-luwak","tag-semarang","tag-shop"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=422"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/422\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}