{"id":46,"date":"2006-02-24T18:07:00","date_gmt":"2006-02-24T16:07:00","guid":{"rendered":"http:\/\/www.mkihr.de\/wordpress\/?p=46"},"modified":"2006-02-24T18:07:00","modified_gmt":"2006-02-24T16:07:00","slug":"ampelmannchen","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2006\/02\/24\/ampelmannchen\/","title":{"rendered":"Ampelm\u00e4nnchen"},"content":{"rendered":"<p><a class=\"tt-flickr\" href=\"http:\/\/www.flickr.com\/photos\/mkihr\/281278547\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" class=\"tt-flickr\" alt=\"P1010453\" style=\"float: left; margin-right: 10px; margin-bottom: 10px\" src=\"http:\/\/static.flickr.com\/91\/281278547_ad43c6d363_m.jpg\" \/><\/a>Die Fu\u00dfg\u00e4ngerampeln hier find ich ja echt abgefahren. Hab die so auch schon in Kuala Lumpur gesehen. Wenn man rot hat, sehen die eigentlich wie ganz normale Ampelm\u00e4nnchen aus. Unseren nicht un\u00e4hnlich. Interessant wird es, wenn es gr\u00fcn wird. Dann wird die L\u00e4nge der Gr\u00fcnphase angezeigt und ein kleines gr\u00fcnes M\u00e4nnchen beginnt loszulaufen. Ja, richtig. Es l\u00e4uft. Der Laufstil \u00e4ndert sich mir verbleibenden Zeit f\u00fcr die Gr\u00fcnphase. Erst l\u00e4uft er wie ein \u00e4lterer Herr so um die achtzig, oder wie Phillip mit Kreuzschmerzen. Sp\u00e4ter bewegt er sich dann mit normalem Tempo und wenn die verbleibende Zeit unter 20 Sekunden angekommen ist f\u00e4ngt das M\u00e4nnchen an zu blinken und zu rennen. Dann wird\u2019s auch f\u00fcr die Fu\u00dfg\u00e4nger Zeit, den Schritt zu beschleunigen. Aufpassen muss man allerdings auch w\u00e4hrend der Gr\u00fcnphase auf abbiegende Autos oder Motorr\u00e4der sonst wird man schon mal \u00fcber den Haufen gefahren.<br \/>\nMan muss noch dazu sagen, dass die Gr\u00fcnphase bei gro\u00dfen Stra\u00dfen schon mal so um die 90 Sekunden lang ist. Man hat dann ja auch 4 Fahrbahnen zu \u00fcberqueren und ca. 100m zur\u00fcckzulegen. Bei verbleibenden 20 Sekunden ist dann schon rennen angesagt.<br \/>\nInteressant ist au\u00dferdem, dass es hier keine einzige Ampel mehr ohne LED Technik gibt. Da ist man hier also auch schneller und moderner als in Deutschland.<br \/>\nIm \u00fcbrigen: Heute morgen gab es hier ein kleines Erdbeben. Ist schon ein merkw\u00fcrdiges Gef\u00fchl, wenn pl\u00f6tzlich das Haus schwankt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Fu\u00dfg\u00e4ngerampeln hier find ich ja echt abgefahren. Hab die so auch schon in Kuala Lumpur gesehen. Wenn man rot hat, sehen die eigentlich wie ganz normale Ampelm\u00e4nnchen aus. Unseren nicht un\u00e4hnlich. Interessant wird es, wenn es gr\u00fcn wird. Dann wird die L\u00e4nge der Gr\u00fcnphase angezeigt und ein kleines gr\u00fcnes M\u00e4nnchen beginnt loszulaufen. Ja, richtig. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-46","post","type-post","status-publish","format-standard","hentry","category-taiwan"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}