{"id":62,"date":"2006-09-25T20:46:52","date_gmt":"2006-09-26T01:46:52","guid":{"rendered":"http:\/\/www.mkihr.de\/wordpress\/?p=62"},"modified":"2006-09-25T20:46:52","modified_gmt":"2006-09-26T01:46:52","slug":"benzinpreise-2","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2006\/09\/25\/benzinpreise-2\/","title":{"rendered":"Benzinpreise"},"content":{"rendered":"<p>Wer denkt in Deutschland sind die Benzinpreise hoch, sollte mal hierher kommen:<br \/>\n<a target=\"_blank\" href=\"http:\/\/www.flickr.com\/photos\/mkihr\/290373877\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" alt=\"P1010908\" class=\"tt-flickr\" src=\"http:\/\/static.flickr.com\/107\/290373877_55189d7395.jpg\" \/><\/a><br \/>\nDer Umtauschkurs liegt etwa bei 4. Der Liter Super kostet also mehr als 3\u20ac. Und das bei den alten Sch\u00fcsseln, die hier so herumfahren. H\u00e4tte ja nicht gedacht, das ich noch mal so viele Ladas auf der Strasse sehe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer denkt in Deutschland sind die Benzinpreise hoch, sollte mal hierher kommen: Der Umtauschkurs liegt etwa bei 4. Der Liter Super kostet also mehr als 3\u20ac. Und das bei den alten Sch\u00fcsseln, die hier so herumfahren. H\u00e4tte ja nicht gedacht, das ich noch mal so viele Ladas auf der Strasse sehe.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-62","post","type-post","status-publish","format-standard","hentry","category-peru"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=62"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/62\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=62"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=62"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}