{"id":756,"date":"2010-07-18T11:03:11","date_gmt":"2010-07-18T09:03:11","guid":{"rendered":"http:\/\/reisen.mkihr.de\/?p=756"},"modified":"2010-07-18T11:03:11","modified_gmt":"2010-07-18T09:03:11","slug":"hitze-in-deutschland","status":"publish","type":"post","link":"https:\/\/reisen.kihr.online\/index.php\/2010\/07\/18\/hitze-in-deutschland\/","title":{"rendered":"Hitze in Deutschland"},"content":{"rendered":"<p style=\"text-align: justify;\">Ganz Deutschland leidet unter der Hitze. Klimaanlagen in Z\u00fcgen fallen aus. Alles jammert, dass es zu warm ist. Wie immer wenn es l\u00e4nger als drei Tage regnet, schneit, warm oder kalt ist, sind offenbar alle mit dem Wetter unzufrieden. Tja, was soll ich denn sagen. Ich bin seit zwei Monaten hier. Keine Wolke am Himmel. Kein Tropfen Regen. Letzte Woche hatten wir reichlich \u00fcber 40 Grad. Diese Woche ist es etwas besser. Wir kommen nur auf 37. Gut ist hier: Es gibt sowohl im B\u00fcro als auch im Hotel Klimaanlagen.<!--more-->[ad]<\/p>\n<p style=\"text-align: justify;\">Schlecht sieht es damit in \u00f6ffentlichen Verkehrsmitteln oder Taxis aus. Da gibt es nur: T\u00fcren und Fenster auf. Das ist bei ca. 45 Grad (wohlgemerkt im Schatten) auch nicht gerade die wahre Freude. In dieser Stadt gibt es praktisch keinen Schatten. Die Sonne gl\u00fcht auf endlos freie Fl\u00e4chen. Es gibt nahezu kein Gr\u00fcn. Keine Springbrunnen die k\u00fchlen. Nichts. Ab und zu ist es mal ein bisschen windig. Aber auch der kommt ja nur aus der umliegenden W\u00fcste und bringt noch mehr W\u00e4rme. Der Wind f\u00fchlt sich an als wenn man vor einem offenen Backofen steht.\u00a0\u00c4hnlich ist es, wenn man den Fahrtwind durch das offene Fenster im Taxi sp\u00fcrt. Man hat das Gef\u00fchl, dass es einem die Haare auf der Haut versengt.<\/p>\n<p style=\"text-align: justify;\">Aber ein Ende ist Abzusehen. Am Freitag geht es wieder Richtung Deutschland. Ein kleiner Zwischenstop in Istanbul um mir die Stadt ein wenig anzusehen und dann bin ich am Freitag Abend wieder zu Hause. Endlich wieder ein bisschen K\u00fchle geniessen.<\/p>\n<p style=\"text-align: justify;\">[ad]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ganz Deutschland leidet unter der Hitze. Klimaanlagen in Z\u00fcgen fallen aus. Alles jammert, dass es zu warm ist. Wie immer wenn es l\u00e4nger als drei Tage regnet, schneit, warm oder kalt ist, sind offenbar alle mit dem Wetter unzufrieden. Tja, was soll ich denn sagen. Ich bin seit zwei Monaten hier. Keine Wolke am Himmel. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,14,21],"tags":[52,54,87,88,123,126,238,239],"class_list":["post-756","post","type-post","status-publish","format-standard","hentry","category-asien","category-mittlerer-osten","category-syrien","tag-asia","tag-asien","tag-damascus","tag-damaskus","tag-heat","tag-hitze","tag-syria","tag-syrien"],"_links":{"self":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/comments?post=756"}],"version-history":[{"count":0,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/posts\/756\/revisions"}],"wp:attachment":[{"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/media?parent=756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/categories?post=756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.kihr.online\/index.php\/wp-json\/wp\/v2\/tags?post=756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}